{"id":54331,"date":"2020-09-01T17:28:55","date_gmt":"2020-09-01T15:28:55","guid":{"rendered":"https:\/\/ecobnb.it\/blog\/?p=54331"},"modified":"2020-11-03T09:49:52","modified_gmt":"2020-11-03T08:49:52","slug":"bosco-arte-stenico","status":"publish","type":"post","link":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/","title":{"rendered":"L&#8217;Arte e la Natura si incontrano nel Bosco Arte Stenico"},"content":{"rendered":"<h2>Il Trentino non \u00e8 solo montagna e natura, ma un territorio ricchissimo di arte e storia. Un castello da fiaba e un percorso di land-art ci portano in viaggio tra arte e natura a Stenico<\/h2>\n<p>In <a href=\"https:\/\/ecobnb.it\/trentino-alto-adige\" target=\"_blank\" rel=\"noopener\"><strong>Trentino<\/strong><\/a>, nel cuore della <strong>biosfera Unesco Alpi Ledrensi e Judicaria<\/strong>, esiste un luogo dove la <strong>natura e l&#8217;arte si incontrano<\/strong>: il <strong>Bosco Arte Stenico<\/strong>, da dove si pu\u00f2 apprezzare il rinomato <strong>castello provinciale<\/strong>.<\/p>\n<h2>Il Castello di Stenico<\/h2>\n<div id=\"attachment_54816\" class=\"thumbnail alignnone\"><img class=\"wp-image-54816 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/09\/castello-di-stenico-870x490.jpg\" alt=\"Castello di Stenico\" width=\"870\" height=\"490\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/09\/castello-di-stenico-870x490.jpg 870w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/09\/castello-di-stenico-570x320.jpg 570w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><div class=\"caption\">Castello di Stenico, foto di Maurizio Corradi, via boscoartestenico.eu<\/div><\/div>\n<p>Il <strong>Castello di Stenico<\/strong> \u00e8 una imponente fortezza raffigurata in una delle immagini del <strong>Ciclo dei mesi di Torre Aquila del Castello del Buonconsiglio<\/strong>, ossia quella con dame e cavalieri che giocano a palle di neve.<\/p>\n<p><img class=\"alignnone wp-image-54761 size-full\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/Venceslao_Gennaio_Castello_Buonconsiglio_Trento_c1400_detail.jpg\" alt=\"Affresco a Torre Aquila, Gennaio. Nobili giocano a palle di neve nei pressi del Castel Stenico\" width=\"500\" height=\"353\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/Venceslao_Gennaio_Castello_Buonconsiglio_Trento_c1400_detail.jpg 500w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/Venceslao_Gennaio_Castello_Buonconsiglio_Trento_c1400_detail-344x243.jpg 344w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>La sua esistenza \u00e8 documentata fin dal 1163 ed \u00e8 stato per secoli residenza del funzionario che esercitava il potere sulle Giudicarie in nome del Principe Vescovo di Trento: il <strong>Capitano delle Giudicarie<\/strong>. Infatti, la sua posizione su uno sperone roccioso consentiva il <strong>controllo delle vie di comunicazione verso il territorio giudicariese<\/strong>. Una <strong>tenebrosa leggenda<\/strong> narra che in una delle sue torri venivano lasciati morire di fame i prigionieri, le cui anime inquiete comparirebbero nelle notti di luna piena.<\/p>\n<p>Oggi il castello ospita <strong>mostre<\/strong>, <strong>arte applicata e contemporanea, concerti e altre performance<\/strong>. Inoltre, conserva una preziosa <strong>sezione archeologica<\/strong> dedicata alla storia locale. <a href=\"https:\/\/www.buonconsiglio.it\/index.php\/Castello-di-Stenico\/informazioni\/orari-e-biglietti\" target=\"_blank\" rel=\"noopener\">Info e orari e tariffe a questo link<\/a>.<\/p>\n<h2>Bosco Arte Stenico<\/h2>\n<p>Il <strong>Bosco Arte Stenico<\/strong> \u00e8 un suggestivo sentiero che si sviluppa nel bosco, in prossimit\u00e0 dell&#8217;abitato di <strong>Stenico<\/strong>, in <strong>Val Giudicarie<\/strong>.<\/p>\n<div id=\"attachment_54756\" class=\"thumbnail alignnone\"><img class=\"wp-image-54756 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/DSC_1266_01-870x490.jpg\" alt=\"Opera di legno nel Bosco Arte Stenico\" width=\"870\" height=\"490\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/DSC_1266_01-870x490.jpg 870w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/DSC_1266_01-570x320.jpg 570w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><div class=\"caption\">Foto via boscoartestenico.eu<\/div><\/div>\n<p>Passeggiando in questo bosco si possono ammirare straordinarie <strong>opere contemporanee<\/strong> create con <strong>materiali naturali<\/strong>, lasciate dagli autori testimoni di questo incontro tra natura e arte. Infatti, il <a href=\"https:\/\/ecobnb.it\/blog\/2018\/09\/legno-arte-riciclo-creativo\/\" target=\"_blank\" rel=\"noopener\"><strong>legno<\/strong><\/a> rappresenta un prezioso dono che ci d\u00e0 il bosco per poterlo trasformare in <strong>pezzi d&#8217;arte<\/strong>, in totale <strong>rispetto della natura<\/strong>. Addirittura si arriva ad apprezzare di pi\u00f9 le opere logorate perch\u00e9 hanno un fascino che va al di l\u00e0 dello spazio-tempo. Inoltre, all&#8217;interno del bosco si vive un&#8217;aria di <strong>serenit\u00e0<\/strong>, ironia e cultura, che si coniugano in maniera piacevolissima.<\/p>\n<div id=\"attachment_54757\" class=\"thumbnail alignnone\"><img class=\"wp-image-54757 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/DSC_1242_01-870x490.jpg\" alt=\"Opera in mezzo al Bosco Arte Stenico\" width=\"870\" height=\"490\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/DSC_1242_01-870x490.jpg 870w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/DSC_1242_01-570x320.jpg 570w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><div class=\"caption\">Foto via boscoartestenico.eu<\/div><\/div>\n<p>Qui il <strong>Castello di Stenico<\/strong>, il <strong><a href=\"https:\/\/ecobnb.it\/blog\/2019\/06\/parco-adamello-brenta-natura\/\" target=\"_blank\" rel=\"noopener\">Parco Adamello Brenta<\/a><\/strong> e <strong>Bosco Arte Stenico<\/strong> formano un <strong>itinerario<\/strong> unico nel suo genere, dove la cultura, l&#8217;arte e la natura si intrecciano in un <strong>paesaggio di una bellezza mozzafiato<\/strong>.<\/p>\n<p>A differenza di <a href=\"https:\/\/ecobnb.it\/blog\/2017\/01\/arte-sella-trentino-bambini\/\" target=\"_blank\" rel=\"noopener\">Arte Sella<\/a> o di altri percorsi di Land Art, Bosco Arte Stenico si caratterizza per la\u00a0totale <strong>naturalit\u00e0 del luogo<\/strong> e delle opere insertite in esso. Plastica, cemento e acciaio sono banditi. Tutto \u00e8 realizzato con materiali naturali e le segnaletiche sono di legno inciso. Le opere d&#8217;arte di legno, cortecce, tronchi e corde\u00a0non vengono nemmeno manutentate e seguono il normale deperimento e ritorno alla terra.<\/p>\n<p>Il percorso artistico \u00e8 stato premiato con la certificazione PEFC per la <strong>sostenibilit\u00e0<\/strong> e con il marchio OPEN per l&#8217;<strong>accessibilit\u00e0<\/strong>. Infatti, il percorso \u00e8 fruibile ai disabili con carozzina anche in autonomia.<\/p>\n<h3>Le edizioni artistiche<\/h3>\n<div id=\"attachment_54803\" class=\"thumbnail alignnone\"><img class=\"wp-image-54803 size-medium\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/opera-arte-legno-536x744.jpg\" alt=\"bosco arte stenico\" width=\"536\" height=\"744\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/opera-arte-legno-536x744.jpg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/opera-arte-legno-768x1066.jpg 768w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/opera-arte-legno-344x478.jpg 344w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/opera-arte-legno.jpg 1257w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><div class=\"caption\">foto via pagina facebook di Bosco Arte Stenico<\/div><\/div>\n<p>Il <strong>tema<\/strong> del 2019 era &#8220;<strong>Su<\/strong>&#8220;, ispirato agli <a href=\"https:\/\/ecobnb.it\/blog\/2018\/11\/strage-di-alberi-dolomiti\/\" target=\"_blank\" rel=\"noopener\">traumatici eventi climatici<\/a> che il bosco ha subito nell&#8217;ottobre 2018. Il titolo si riferisce all&#8217;innato <strong>entusiasmo che hanno i bambini<\/strong> anche di fronte alle difficolt\u00e0, un pregio che noi adulti col tempo perdiamo. Un bambino non si rassegna davanti a nulla ed \u00e8 proprio questo l&#8217;<strong>atteggiamento giusto per rinascere<\/strong> e continuare a vivere il bosco.<\/p>\n<p>Purtroppo, dato il protrarsi dell&#8217;emergenza sanitaria, l&#8217;edizione artistica del 2020<strong> non avr\u00e0 luogo<\/strong>. Ci attender\u00e0 una nuova manifestazione l&#8217;anno prossimo: gli artisti saranno invitati a esprimersi sul tema della &#8220;<strong>Metamorfosi<\/strong>&#8220;.<\/p>\n<h2>Conclusione<\/h2>\n<div id=\"attachment_54802\" class=\"thumbnail alignnone\"><img class=\"wp-image-54802 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/bosco-arte-stenico-870x490.jpg\" alt=\"bosco arte stenico\" width=\"870\" height=\"490\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/bosco-arte-stenico-870x490.jpg 870w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/bosco-arte-stenico-536x302.jpg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/bosco-arte-stenico-768x432.jpg 768w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/bosco-arte-stenico-570x320.jpg 570w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/bosco-arte-stenico-344x194.jpg 344w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/bosco-arte-stenico.jpg 2048w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><div class=\"caption\">foto via pagina facebook di Bosco Arte Stenico<\/div><\/div>\n<p>In questo luogo il principio \u00e8 proprio quello che pi\u00f9 ci piace: la <strong>sostenibilit\u00e0<\/strong>. Utilizzando <strong>prodotti naturali<\/strong>, ad un certo punto l&#8217;<strong>opera naturalmente si degrada <\/strong>nel paesaggio e ne diventa parte. Ci\u00f2 rappresenta la <strong>caratteristica principale della natura<\/strong>: si riprende quello che gentilmente ci ha offerto per riuscire a creare le opere. Qualcosa che c&#8217;\u00e8 e poi sparisce, proprio come il <strong>ciclo della la vita<\/strong>.<\/p>\n<p><strong>Info: <a href=\"https:\/\/www.boscoartestenico.eu\/\" target=\"_blank\" rel=\"noopener\">boscoartestenico.eu<\/a><\/strong><\/p>\n<p><em>Immagine di copertina: foto via boscoartestenico.eu<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Trentino non \u00e8 solo montagna e natura, ma un territorio ricchissimo di arte e storia. Un castello da fiaba e un percorso di land-art ci portano in viaggio tra arte e natura a Stenico In Trentino, nel cuore della biosfera Unesco Alpi Ledrensi e Judicaria, esiste un luogo dove la natura e l&#8217;arte si [&hellip;]<\/p>\n","protected":false},"author":140,"featured_media":54759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[233,232],"tags":[3944,3354,1121],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;Arte e la Natura si incontrano nel Bosco Arte Stenico - Ecobnb<\/title>\n<meta name=\"description\" content=\"Conciliare arte e natura \u00e8 il massimo che un luogo possa offrire. Scopri le opere d&#039;arte nel percorso Arte Stenico, create in armonia con la natura!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Arte e la Natura si incontrano nel Bosco Arte Stenico - Ecobnb\" \/>\n<meta property=\"og:description\" content=\"Conciliare arte e natura \u00e8 il massimo che un luogo possa offrire. Scopri le opere d&#039;arte nel percorso Arte Stenico, create in armonia con la natura!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/viaggiverdi\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-01T15:28:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-03T08:49:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/Opera-Corradi-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Cristina\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Cristina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Arte e la Natura si incontrano nel Bosco Arte Stenico - Ecobnb","description":"Conciliare arte e natura \u00e8 il massimo che un luogo possa offrire. Scopri le opere d'arte nel percorso Arte Stenico, create in armonia con la natura!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/","og_locale":"it_IT","og_type":"article","og_title":"L'Arte e la Natura si incontrano nel Bosco Arte Stenico - Ecobnb","og_description":"Conciliare arte e natura \u00e8 il massimo che un luogo possa offrire. Scopri le opere d'arte nel percorso Arte Stenico, create in armonia con la natura!","og_url":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/viaggiverdi","article_published_time":"2020-09-01T15:28:55+00:00","article_modified_time":"2020-11-03T08:49:52+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2020\/08\/Opera-Corradi-.jpg","type":"image\/jpeg"}],"author":"Maria Cristina","twitter_misc":{"Written by":"Maria Cristina","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/#article","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/"},"author":{"name":"Maria Cristina","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/person\/194c78ae3697bdee0299af536591643c"},"headline":"L&#8217;Arte e la Natura si incontrano nel Bosco Arte Stenico","datePublished":"2020-09-01T15:28:55+00:00","dateModified":"2020-11-03T08:49:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/"},"wordCount":705,"publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"keywords":["bosco arte stenico","meraviglie della natura","Trentino"],"articleSection":["itinerari","news ed eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/","url":"https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/","name":"L'Arte e la Natura si incontrano nel Bosco Arte Stenico - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/#website"},"datePublished":"2020-09-01T15:28:55+00:00","dateModified":"2020-11-03T08:49:52+00:00","description":"Conciliare arte e natura \u00e8 il massimo che un luogo possa offrire. Scopri le opere d'arte nel percorso Arte Stenico, create in armonia con la natura!","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.it\/blog\/2020\/09\/bosco-arte-stenico\/"]}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.it\/blog\/#website","url":"https:\/\/ecobnb.it\/blog\/","name":"Ecobnb","description":"Trova il tuo Alloggio Ecosostenibile","publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecobnb.it\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/viaggiverdi"]},{"@type":"Person","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/person\/194c78ae3697bdee0299af536591643c","name":"Maria Cristina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f66f8e721d0c282d9aceb798818b5a2?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f66f8e721d0c282d9aceb798818b5a2?s=96&d=monsterid&r=g","caption":"Maria Cristina"},"description":"I was born around the sunny Sicilian countryside and grown up between the majestic mountains of Trentino. From an early age, I've always been fascinated by the cultural diversity of our country, from the north to the south. I have a big passion for languages and I dream about being able to discover every inch of the earth, respecting the environment and enhancing the unicity of the human race.","url":"https:\/\/ecobnb.it\/blog\/author\/cristinamaria\/"}]}},"_links":{"self":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts\/54331"}],"collection":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/comments?post=54331"}],"version-history":[{"count":15,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts\/54331\/revisions"}],"predecessor-version":[{"id":55979,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts\/54331\/revisions\/55979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media\/54759"}],"wp:attachment":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media?parent=54331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/categories?post=54331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/tags?post=54331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}