{"id":13655,"date":"2015-09-12T17:51:59","date_gmt":"2015-09-12T15:51:59","guid":{"rendered":"https:\/\/ecobnb.it\/blog\/?p=13655"},"modified":"2020-11-24T17:09:51","modified_gmt":"2020-11-24T16:09:51","slug":"agricampeggio","status":"publish","type":"post","link":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/","title":{"rendered":"Pronti per l&#8217;agricampeggio? Ecco 6 proposte da non perdere"},"content":{"rendered":"<p>Paolo ha incontrato Rosa, la sua attuale moglie, in <strong>campeggio<\/strong>.\u00a0Era tutto pi\u00f9 semplice a fine anni \u201890: poche centinaia di Euro, una<strong> tenda<\/strong>, uno zaino e via verso la Croazia o le isole greche.\u00a0Poi le cose sono diventate un po\u2019 pi\u00f9 complesse: il matrimonio, il mutuo, il lavoro, i bimbi e addio al senso di libert\u00e0 e di unione con la <strong>Natura<\/strong>.\u00a0 Cos\u00ec quando Rosa ha proposto un <strong>agricampeggio<\/strong>, nonostante la sensazione che non fosse esattamente la stessa cosa, Paolo ha detto \u201cProviamo\u201d con la speranza di provare di nuovo quel senso di libert\u00e0 dai ritmi imposti e una maggiore attenzione per ritmi pi\u00f9 naturali.<\/p>\n<p>Se anche voi siete alla ricerca di un buon compromesso tra la <strong>comodit\u00e0 di un agriturismo<\/strong> e il senso di <strong>contatto con la Natura <\/strong>di un campeggio, ecco la nostra selezione per trovare un agricampeggio sia che andiate al Nord, al Centro o al Sud.<\/p>\n<p><img class=\"alignnone wp-image-13744 size-full\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Agricampeggi.jpg\" alt=\"6 Agricampeggi ecofriendly in Italia\" width=\"800\" height=\"1200\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Agricampeggi.jpg 800w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Agricampeggi-536x804.jpg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Agricampeggi-344x516.jpg 344w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>6\u00a0Agricampeggi Biologici in\u00a0Italia, dove la sveglia la da&#8217; il gallo!<\/h2>\n<p>Cos&#8217;\u00e8 un <strong>Agri-campeggio<\/strong>? E&#8217; un <strong>campeggio<\/strong> in fattoria. Un agriturismo che offre ai\u00a0suoi ospiti la possibilit\u00e0 di campeggiare all&#8217;aria aperta, mettendo a disposizione i servizi igenici, l&#8217;energia elettrica, e gli altri servizi della struttura. A volte c&#8217;\u00e8 il ristorante, altre volte la piscina, l&#8217;orto biologico\u00a0o il barbecue. Quasi sempre trovate tanta natura e animali, bellissimi paesaggi e un&#8217;ambiente autentico.<\/p>\n<p>Questo <strong>turismo all&#8217;aria aperta<\/strong> vi riporta alle origini vere del campeggio. La tenda \u00e8 circondata da prati e boschi, gli ospiti sono pochi e i\u00a0servizi sono essenziali. In pi\u00f9 vi sentirete\u00a0sentire parte della vita della fattoria: osserverete\u00a0gli animali, potrete acquistare\u00a0i prodotti tipici, e vi sveglierete con il canto del gallo!<\/p>\n<p>Se siete alla ricerca di un <strong>agricampeggio eco-sostenibile<\/strong>, date un&#8217;occhiata a queste 6 possibilit\u00e0\u00a0in <strong>fattorie biologiche<\/strong>, dal Carso alla Sardegna, e scegliete quella pi\u00f9 adatta per voi.<\/p>\n<h2>1. Qui dormi tra i pascoli dell&#8217;Altopiano del Carso<\/h2>\n<div id=\"attachment_13732\" class=\"thumbnail alignnone\"><img class=\"wp-image-13732 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Parco-Rurale_Alture-di-Polazzo-840x490.jpg\" alt=\"Agricampeggio Parco-Rurale Alture di Polazzo, Gorizia\" width=\"840\" height=\"490\" \/><div class=\"caption\">Agricampeggio Parco-Rurale Alture di Polazzo, Gorizia<\/div><\/div>\n<p>Sull\u2019altopiano del Carso, a pochi chilometri dalla mitteleuropea <strong>Trieste<\/strong> ecco il Parco Rurale Alture di Polazzo.<\/p>\n<p>L\u00ec vi aspettano 15 piazzole con <strong>vista strepitosa sui pendii rocciosi<\/strong> e sui campi verdi senza nessun genere di disturbo se non quello legato al rumore del vento e dei rapaci.<\/p>\n<p>E se la vita di campagna \u00e8 il vostro ideale, perch\u00e8 non raggiungere i <strong>pascoli<\/strong> in altura? Lo staff del Parco Rurale sar\u00e0 lieto di darvi tutte le informazioni necessarie.<\/p>\n<p><strong>Ci piace perch\u00e9:<\/strong> se siete attenti alle tematiche circa l\u2019inquinamento atmosferico da gas di scarico, potrete raggiungere il Parco con la vostra <strong>auto elettrica<\/strong> o noleggiarne una per l\u2019occasione e vedere come va.<\/p>\n<p>Il Parco \u00e8 dotato di piazzole per la <strong>ricarica dei veicoli a energia elettrica<\/strong>.<\/p>\n<h4>Info: <a href=\"https:\/\/ecobnb.it\/gorizia\/agriturismo.campeggio\/parco-rurale-alture-di-polazzo\" target=\"_blank\" rel=\"noopener\">Parco Rurale Alture di Polazzo, Fogliano Redipuglia (Gorizia), Friuli Venezia Giulia<\/a><\/h4>\n<h2>2. Qui ritrovi la natura e il senso dello stare insieme<\/h2>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-13655 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/yuptala\/#main'><img width=\"270\" height=\"200\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/yuptala-270x200.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Agricampeggio Yuptala, Toscana\" aria-describedby=\"gallery-1-13735\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13735'>\n\t\t\t\tCampeggio nel verde\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/yuptala-2\/#main'><img width=\"270\" height=\"200\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/yuptala-2-270x200.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Agricampeggio Yuptala, Toscana\" aria-describedby=\"gallery-1-13734\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13734'>\n\t\t\t\tAgricampeggio Yuptala, Terriciola, Pisa\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/yuptala-3\/#main'><img width=\"270\" height=\"200\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/yuptala-3-270x200.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Agricampeggio Yuptala, Toscana\" aria-describedby=\"gallery-1-13733\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13733'>\n\t\t\t\tcampo da pallavolo e cavalli\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Tutto nacque, qualche anno fa, dall\u2019idea di aprire un\u2019<strong>azienda agricola<\/strong> ispirata all\u2019<strong>ecologia<\/strong> e al rispetto della natura e dei suoi ritmi, prima di tutto.<\/p>\n<p>A questo progetto iniziale si \u00e8 unito, oggi, un <strong>agricampeggio<\/strong> con larghe piazzole separate da siepi di <strong>erbe aromatiche<\/strong>, acqua calda prodotta soprattutto grazie ai <strong>pannelli solari<\/strong> e un <strong>sistema di raccolta differenziata<\/strong> che ricicla e separa 80% dello sporco prodotto.<\/p>\n<p><strong>Ci piace perch\u00e9:<\/strong> c\u2019\u00e8 una tenda centrale enorme con <strong>amache<\/strong>, tavoli e sedie che serve da spazio comune. D\u2019altrocanto Yuptala significa \u201cinsieme\u201d in idioma Lakota e nella tenda si sta insieme, appunto.<\/p>\n<h4><strong>Info: <a href=\"https:\/\/ecobnb.it\/pisa\/campeggio\/agri-yuptala\" target=\"_blank\" rel=\"noopener\">Agricampeggio Yuptala, Terricciola (Pisa), Toscana<\/a><\/strong><\/h4>\n<h2>3. Qui vivi una vacanza\u00a0open air e impari a cavalcare<\/h2>\n<div id=\"attachment_13736\" class=\"thumbnail alignnone\"><img class=\"wp-image-13736 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/cavallo-foto-di-Francesco-Belsito-800x490.jpg\" alt=\"cavallo in agri-campeggio\" width=\"800\" height=\"490\" \/><div class=\"caption\">Cavallo, foto di Francesco Belsito, via flickr<\/div><\/div>\n<p>Se vi piacciono i cavalli e cavalcare, siete arrivati nel posto giusto.<br \/>\nQui vi aspetta una vera <strong>vacanza in stile cowboy<\/strong> o meglio in stile \u201cbuttero\u201d.\u00a0I butteri, responsabili di spostare e guidare le mandrie tra i vari pascoli e allevamenti, sono ottimi cavalieri abituati a cavarsela in ogni occasione, cos\u00ec abili che si racconta batterono anche <em>Buffalo Bill<\/em> quando venne in tourn\u00e9 in Italia.<\/p>\n<p>Una vacanza all&#8217;agriturismo<strong> Il Cornacchino<\/strong> vi permetter\u00e0 di imparare a cavalcare o migliorare il vostro stile, ma soprattutto di immergervi nella natura <strong>Toscana<\/strong>.<\/p>\n<p><strong>Ci piace perch\u00e9: <\/strong>a met\u00e0 strada tra Viterbo e Siena, unirete l\u2019immersione nella Natura a quella nella cultura.<\/p>\n<h4>Info:\u00a0<a href=\"https:\/\/ecobnb.it\/grosseto\/agriturismo.campeggio\/il-cornacchino\" target=\"_blank\" rel=\"noopener\">Agricampeggio il Cornacchino, Castell\u2019Azzaro (Grosseto), Toscana<\/a><\/h4>\n<h2>4. Qui scopri\u00a0il Parco dei Cinque Laghi di Ivrea<\/h2>\n<div id=\"attachment_13737\" class=\"thumbnail alignnone\"><img class=\"wp-image-13737 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/La-campagnetta-870x490.jpg\" alt=\"Agricampeggio La campagnetta, Piemonte\" width=\"870\" height=\"490\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/La-campagnetta-870x490.jpg 870w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/La-campagnetta-570x320.jpg 570w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><div class=\"caption\">Agricampeggio presso l&#8217;agriturismo La Campagnetta, Chiaverano, Torino, Piemonte<\/div><\/div>\n<p>Nel cuore del <strong>Parco dei 5 laghi<\/strong>\u00a0La Campagnetta \u00e8 adagiata sulla morbida erba dei pascoli attorno a Torino e immersa tra orti e frutteti.<\/p>\n<p>Qui non sarete svegliati dal chicchirich\u00ec del gallo, ma provate a dimenticare o a ritardare la dose mattutina di carezze all\u2019<strong>asina Rita<\/strong> e sentirete che musica.<\/p>\n<p><strong>Ci piace perch\u00e9:<\/strong> con il primo fresco di questa fine estate, trovare un camino accesso \u00e8 un piacere.<\/p>\n<h4>Info: <a href=\"https:\/\/ecobnb.it\/torino\/agriturismo\/la-campagnetta\" target=\"_blank\" rel=\"noopener\">Agriturismo La Campagnetta, Chiaverano (Torino), Piemonte<\/a><\/h4>\n<h2>5. Qui\u00a0dormi\u00a0tra aranci e limoni\u00a0alle pendici dell&#8217;Etna<\/h2>\n<h2><img class=\"wp-image-13738 size-full\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Eco-Casa-sullEtna.jpeg\" alt=\"Eco Casa sull'Etna, Catania, offre anche la possibilit\u00e0 di soggiornare in Agricampeggio\" width=\"770\" height=\"431\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Eco-Casa-sullEtna.jpeg 770w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Eco-Casa-sullEtna-536x300.jpeg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Eco-Casa-sullEtna-570x320.jpeg 570w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Eco-Casa-sullEtna-344x193.jpeg 344w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/h2>\n<p>Vista dall&#8217; Eco\u00a0Casa sull&#8217;Etna, Catania<\/p>\n<p>A met\u00e0 strada dalla bocca dell\u2019<strong>Etna<\/strong> ecco una dimora immersa nello spirito del luogo: <strong>aranceti, limonaie, orti e frutteti<\/strong> per accogliere voi e la vostra tenda.<\/p>\n<p><strong>Ci piace perch\u00e9:<\/strong> c\u2019\u00e8 un \u2018enorme cucina comune in cui si organizzano lezioni e seminari di arte culinaria sicula con tutti i migliori ingredienti di questa terra.<\/p>\n<h4>Info: \u00a0<a href=\"https:\/\/ecobnb.it\/catania\/agriturismo\/eco-casa-sull-etna\" target=\"_blank\" rel=\"noopener\">Ecocasa sull\u2019Etna, Mascali (Catania), Sicilia<\/a><\/h4>\n<h2>6. Qui assapori il gusto della Sardegna meno nota<\/h2>\n<div id=\"attachment_13739\" class=\"thumbnail alignnone\"><img class=\"wp-image-13739 size-large\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Mungitura-Agripaules-870x490.jpg\" alt=\"Mungitura all'agriturismo e agricampeggio Agripaules\" width=\"870\" height=\"490\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Mungitura-Agripaules-870x490.jpg 870w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Mungitura-Agripaules-570x320.jpg 570w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><div class=\"caption\">Mungitura all&#8217;agriturismo e agricampeggio Agripaules, foto di Emilio Landolfi<\/div><\/div>\n<p>Lontani dalla Costa Smeralda, ma sempre in un luogo magnifico, a pochi chilometri dal mare del <strong>golfo di Orosei<\/strong> e dai misteriosi <strong>nuraghi e dolmen<\/strong> che disseminano l\u2019altopiano sta Agripaules, un <strong>agricampeggio<\/strong> per assaporare tempi e gusti di una Sardegna magica e meno turistica.<\/p>\n<p><strong>Ci piace perch\u00e9:<\/strong> non vediamo l\u2019ora di fare trekking con gli asinelli sardi.<\/p>\n<h4>Info:\u00a0<a href=\"https:\/\/ecobnb.it\/nuoro\/agriturismo\/agripaules\" target=\"_blank\" rel=\"noopener\">Agripaules, Porgali (Nuoro), Sardegna<\/a><\/h4>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-13655 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/escursione-con-gli-asinelli-a-agripaules-vicino-a-nuoro\/#main'><img width=\"270\" height=\"200\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/08\/Escursione-con-gli-asinelli-a-Agripaules-vicino-a-Nuoro-270x200.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Escursione con gli asinelli a Agripaules, vicino a Nuoro\" aria-describedby=\"gallery-2-13662\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-13662'>\n\t\t\t\tEscursione con gli asinelli a Agripaules, vicino a Nuoro\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/agripaules-asinelli\/#main'><img width=\"270\" height=\"200\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/Agripaules-asinelli-270x200.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Asinelli all&#039;Agricampeggio Agripaules\" aria-describedby=\"gallery-2-13741\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-13741'>\n\t\t\t\tAsinelli di Agripaules\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/agripaules\/#main'><img width=\"270\" height=\"200\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/09\/agripaules-270x200.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Agricampeggio Agripaules\" aria-describedby=\"gallery-2-13740\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-13740'>\n\t\t\t\tPaesaggio e mare\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<h4><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Paolo ha incontrato Rosa, la sua attuale moglie, in campeggio.\u00a0Era tutto pi\u00f9 semplice a fine anni \u201890: poche centinaia di Euro, una tenda, uno zaino e via verso la Croazia o le isole greche.\u00a0Poi le cose sono diventate un po\u2019 pi\u00f9 complesse: il matrimonio, il mutuo, il lavoro, i bimbi e addio al senso di [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":13677,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[235,254],"tags":[1635,1754,1753,1752,1538,1750,1751,1265,1755],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pronti per l&#039;agricampeggio? Ecco 6 proposte da non perdere - Ecobnb<\/title>\n<meta name=\"description\" content=\"A contatto con la Natura e con i ritmi della fattoria: \u00e8 l&#039;agricampeggio. Ecco le novit\u00e0 passando da Nord a Sud, senza dimenticare l&#039;attenzione all&#039;ambiente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronti per l&#039;agricampeggio? Ecco 6 proposte da non perdere - Ecobnb\" \/>\n<meta property=\"og:description\" content=\"A contatto con la Natura e con i ritmi della fattoria: \u00e8 l&#039;agricampeggio. Ecco le novit\u00e0 passando da Nord a Sud, senza dimenticare l&#039;attenzione all&#039;ambiente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/viaggiverdi\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-12T15:51:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-24T16:09:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/08\/agricampeggio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristiana Pedrali\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiana Pedrali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pronti per l'agricampeggio? Ecco 6 proposte da non perdere - Ecobnb","description":"A contatto con la Natura e con i ritmi della fattoria: \u00e8 l'agricampeggio. Ecco le novit\u00e0 passando da Nord a Sud, senza dimenticare l'attenzione all'ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/","og_locale":"it_IT","og_type":"article","og_title":"Pronti per l'agricampeggio? Ecco 6 proposte da non perdere - Ecobnb","og_description":"A contatto con la Natura e con i ritmi della fattoria: \u00e8 l'agricampeggio. Ecco le novit\u00e0 passando da Nord a Sud, senza dimenticare l'attenzione all'ambiente","og_url":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/viaggiverdi","article_published_time":"2015-09-12T15:51:59+00:00","article_modified_time":"2020-11-24T16:09:51+00:00","og_image":[{"width":1170,"height":490,"url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/08\/agricampeggio.jpg","type":"image\/jpeg"}],"author":"Cristiana Pedrali","twitter_misc":{"Written by":"Cristiana Pedrali","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/#article","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/"},"author":{"name":"Cristiana Pedrali","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/person\/1d331edc9a95aa57b2f43c890b86a406"},"headline":"Pronti per l&#8217;agricampeggio? Ecco 6 proposte da non perdere","datePublished":"2015-09-12T15:51:59+00:00","dateModified":"2020-11-24T16:09:51+00:00","mainEntityOfPage":{"@id":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/"},"wordCount":988,"publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"keywords":["agri-campeggio","Agricampeggio Il Cornacchino","Agricampeggio Yupptala","Agripaules","agriturismi biologici","Agriturismo La Campagnetta","Ecocasa sull\u2019Etna","estate","Parco Rurale Alture di Polazzo"],"articleSection":["vivere e viaggiare verde","weekend green"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/","url":"https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/","name":"Pronti per l'agricampeggio? Ecco 6 proposte da non perdere - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/#website"},"datePublished":"2015-09-12T15:51:59+00:00","dateModified":"2020-11-24T16:09:51+00:00","description":"A contatto con la Natura e con i ritmi della fattoria: \u00e8 l'agricampeggio. Ecco le novit\u00e0 passando da Nord a Sud, senza dimenticare l'attenzione all'ambiente","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.it\/blog\/2015\/09\/agricampeggio\/"]}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.it\/blog\/#website","url":"https:\/\/ecobnb.it\/blog\/","name":"Ecobnb","description":"Trova il tuo Alloggio Ecosostenibile","publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecobnb.it\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/viaggiverdi"]},{"@type":"Person","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/person\/1d331edc9a95aa57b2f43c890b86a406","name":"Cristiana Pedrali","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/96eb92a9db72dfb627f9abf1bf1d4625?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96eb92a9db72dfb627f9abf1bf1d4625?s=96&d=monsterid&r=g","caption":"Cristiana Pedrali"},"description":"\"Amare il proprio lavoro \u00e8 la cosa che si avvicina di pi\u00f9 alla felicit\u00e0 sulla terra\" (Rita Levi Montalcini) e \".. perch\u00e8 quando le persone vere cadono nella vita reale si rimettono in piedi e riprendono a camminare\" (Carrie Bradshaw \"Sex and the city\"): questi sono i miei due mantra. Io sono un p\u00f2 cos\u00ec: mi muovo tra il serio ed il faceto per restare a galla tra mille interessi ed impegni e riuscire a sorridere. Ho lavorato e lavoro nel settore del turismo e del web ed ogni tanto cerco un p\u00f2 di ossigeno nella scrittura e nei viaggi!","sameAs":["https:\/\/twitter.com\/CriPedrali"],"url":"https:\/\/ecobnb.it\/blog\/author\/cristiana\/"}]}},"_links":{"self":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts\/13655"}],"collection":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/comments?post=13655"}],"version-history":[{"count":11,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts\/13655\/revisions"}],"predecessor-version":[{"id":56474,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/posts\/13655\/revisions\/56474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media\/13677"}],"wp:attachment":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media?parent=13655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/categories?post=13655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/tags?post=13655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}