{"id":7731,"date":"2014-05-06T17:07:40","date_gmt":"2014-05-06T17:07:40","guid":{"rendered":"http:\/\/blog.viaggiverdi.it\/wp-content\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg"},"modified":"2014-05-06T17:07:40","modified_gmt":"2014-05-06T17:07:40","slug":"32-hawaii-paniolo-greens-going-green-shellvacationshospitality","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.it\/blog\/2014\/05\/tetto-verde-vantaggi\/32-hawaii-paniolo-greens-going-green-shellvacationshospitality\/#main","title":{"rendered":"32 Hawaii Paniolo Greens Going Green-ShellVacationsHospitality"},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>32 Hawaii Paniolo Greens Going Green-ShellVacationsHospitality - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"32 Hawaii Paniolo Greens Going Green-ShellVacationsHospitality - Ecobnb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/viaggiverdi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"32 Hawaii Paniolo Greens Going Green-ShellVacationsHospitality - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"32 Hawaii Paniolo Greens Going Green-ShellVacationsHospitality - Ecobnb","og_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/viaggiverdi","og_image":[{"width":1024,"height":768,"url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg","name":"32 Hawaii Paniolo Greens Going Green-ShellVacationsHospitality - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/#website"},"datePublished":"2014-05-06T17:07:40+00:00","dateModified":"2014-05-06T17:07:40+00:00","breadcrumb":{"@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Non solo un trend, tutti i vantaggi del tetto verde","item":"https:\/\/ecobnb.it\/blog\/2014\/05\/tetto-verde-vantaggi\/"},{"@type":"ListItem","position":2,"name":"32 Hawaii Paniolo Greens Going Green-ShellVacationsHospitality"}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.it\/blog\/#website","url":"https:\/\/ecobnb.it\/blog\/","name":"Ecobnb","description":"Trova il tuo Alloggio Ecosostenibile","publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecobnb.it\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/viaggiverdi"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg'><img width=\"536\" height=\"402\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-536x402.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-536x402.jpg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-344x258.jpg 344w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg 1024w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":768,"file":"2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg","sizes":{"thumbnail":{"file":"32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-270x200.jpg","width":270,"height":200,"filesize":23808,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-270x200.jpg"},"medium":{"file":"32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-536x402.jpg","width":536,"height":402,"filesize":85641,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-536x402.jpg"},"large":{"file":"32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-870x490.jpg","width":870,"height":490,"filesize":170363,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-870x490.jpg"},"wide":{"file":"32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-1024x490.jpg","width":1024,"height":490,"filesize":230473,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-1024x490.jpg"},"half":{"file":"32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-570x320.jpg","width":570,"height":320,"filesize":78406,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-570x320.jpg"},"portrait":{"file":"32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-344x258.jpg","width":344,"height":258,"filesize":37837,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality-344x258.jpg"},"full":{"file":"32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""},"filesize":645969},"post":7697,"source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2014\/05\/32-Hawaii-Paniolo-Greens-Going-Green-ShellVacationsHospitality.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media\/7731"}],"collection":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/users\/3"}]}}