{"id":32034,"date":"2018-05-28T17:42:44","date_gmt":"2018-05-28T15:42:44","guid":{"rendered":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg"},"modified":"2018-05-28T17:43:44","modified_gmt":"2018-05-28T15:43:44","slug":"pineta_di_classe-7","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.it\/blog\/2018\/07\/camminare-benefici\/pineta_di_classe-7\/#main","title":{"rendered":"Pineta_di_Classe-7"},"author":76,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pineta_di_Classe-7 - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pineta_di_Classe-7 - Ecobnb\" \/>\n<meta property=\"og:description\" content=\"Pineta di Classe, nel Parco del Delta del Po, foto via Wikimedia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/viaggiverdi\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-28T15:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pineta_di_Classe-7 - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Pineta_di_Classe-7 - Ecobnb","og_description":"Pineta di Classe, nel Parco del Delta del Po, foto via Wikimedia","og_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/viaggiverdi","article_modified_time":"2018-05-28T15:43:44+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg","name":"Pineta_di_Classe-7 - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/#website"},"datePublished":"2018-05-28T15:42:44+00:00","dateModified":"2018-05-28T15:43:44+00:00","breadcrumb":{"@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Camminare fa&#8217; bene: ecco tutti i benefici + 5 buone abitudini da adottare subito!","item":"https:\/\/ecobnb.it\/blog\/2018\/07\/camminare-benefici\/"},{"@type":"ListItem","position":2,"name":"Pineta_di_Classe-7"}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.it\/blog\/#website","url":"https:\/\/ecobnb.it\/blog\/","name":"Ecobnb","description":"Trova il tuo Alloggio Ecosostenibile","publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecobnb.it\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/viaggiverdi"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg'><img width=\"536\" height=\"402\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-536x402.jpg\" class=\"attachment-medium size-medium\" alt=\"Pineta di Classe, nel Parco del Delta del Po, foto via Wikimedia\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-536x402.jpg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-344x258.jpg 344w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg 800w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Pineta di Classe, nel Parco del Delta del Po, foto via Wikimedia<\/p>\n"},"alt_text":"Pineta di Classe, nel Parco del Delta del Po, foto via Wikimedia","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":600,"file":"2018\/05\/Pineta_di_Classe-7.jpg","sizes":{"thumbnail":{"file":"Pineta_di_Classe-7-270x200.jpg","width":270,"height":200,"filesize":18723,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-270x200.jpg"},"medium":{"file":"Pineta_di_Classe-7-536x402.jpg","width":536,"height":402,"filesize":70517,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-536x402.jpg"},"large":{"file":"Pineta_di_Classe-7-800x490.jpg","width":800,"height":490,"filesize":158613,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-800x490.jpg"},"wide":{"file":"Pineta_di_Classe-7-800x490.jpg","width":800,"height":490,"filesize":158613,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-800x490.jpg"},"half":{"file":"Pineta_di_Classe-7-570x320.jpg","width":570,"height":320,"filesize":68295,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-570x320.jpg"},"portrait":{"file":"Pineta_di_Classe-7-344x258.jpg","width":344,"height":258,"filesize":30138,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7-344x258.jpg"},"full":{"file":"Pineta_di_Classe-7.jpg","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"filesize":126371},"post":31913,"source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2018\/05\/Pineta_di_Classe-7.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media\/32034"}],"collection":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/users\/76"}]}}