{"id":25856,"date":"2017-05-21T13:53:13","date_gmt":"2017-05-21T11:53:13","guid":{"rendered":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg"},"modified":"2017-05-23T09:55:15","modified_gmt":"2017-05-23T07:55:15","slug":"img_20170520_110507","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.it\/blog\/img_20170520_110507\/","title":{"rendered":"Le Serre dei Giardini &#8211; Bologna"},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Serre dei Giardini - Bologna - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Serre dei Giardini - Bologna - Ecobnb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/viaggiverdi\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-23T07:55:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-870x490.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Serre dei Giardini - Bologna - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Le Serre dei Giardini - Bologna - Ecobnb","og_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/viaggiverdi","article_modified_time":"2017-05-23T07:55:15+00:00","og_image":[{"width":870,"height":490,"url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-870x490.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg","name":"Le Serre dei Giardini - Bologna - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/#website"},"datePublished":"2017-05-21T11:53:13+00:00","dateModified":"2017-05-23T07:55:15+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg"]}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.it\/blog\/#website","url":"https:\/\/ecobnb.it\/blog\/","name":"Ecobnb","description":"Trova il tuo Alloggio Ecosostenibile","publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecobnb.it\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/viaggiverdi"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg'><img width=\"536\" height=\"402\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-536x402.jpg\" class=\"attachment-medium size-medium\" alt=\"Le Serre dei Giardini - Bologna\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-536x402.jpg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-344x258.jpg 344w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Le Serre dei Giardini - Bologna","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4160,"height":3120,"file":"2017\/05\/IMG_20170520_110507.jpg","sizes":{"thumbnail":{"file":"IMG_20170520_110507-270x200.jpg","width":270,"height":200,"filesize":21849,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-270x200.jpg"},"medium":{"file":"IMG_20170520_110507-536x402.jpg","width":536,"height":402,"filesize":78278,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-536x402.jpg"},"large":{"file":"IMG_20170520_110507-870x490.jpg","width":870,"height":490,"filesize":153183,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-870x490.jpg"},"wide":{"file":"IMG_20170520_110507-1170x490.jpg","width":1170,"height":490,"filesize":194313,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-1170x490.jpg"},"half":{"file":"IMG_20170520_110507-570x320.jpg","width":570,"height":320,"filesize":69229,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-570x320.jpg"},"portrait":{"file":"IMG_20170520_110507-344x258.jpg","width":344,"height":258,"filesize":34590,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507-344x258.jpg"},"full":{"file":"IMG_20170520_110507.jpg","width":4160,"height":3120,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg"}},"image_meta":{"aperture":2,"credit":"","camera":"HUAWEI TAG-L01","caption":"","created_timestamp":1495278308,"copyright":"","focal_length":"3.5","iso":"97","shutter_speed":"0.000972","title":"","orientation":1},"filesize":5462379},"post":null,"source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2017\/05\/IMG_20170520_110507.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media\/25856"}],"collection":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/users\/3"}]}}