{"id":14213,"date":"2015-10-31T12:19:34","date_gmt":"2015-10-31T11:19:34","guid":{"rendered":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg"},"modified":"2015-10-31T12:20:00","modified_gmt":"2015-10-31T11:20:00","slug":"nikon-f-3ais-micro-nikkor-200mm-f4velvia","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.it\/blog\/2015\/10\/itinerari-foliage-italia\/nikon-f-3ais-micro-nikkor-200mm-f4velvia\/#main","title":{"rendered":""},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>- Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Ecobnb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/viaggiverdi\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-31T11:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"- Ecobnb","og_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/viaggiverdi","article_modified_time":"2015-10-31T11:20:00+00:00","og_image":[{"width":1170,"height":490,"url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg","name":"- Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.it\/blog\/#website"},"datePublished":"2015-10-31T11:19:34+00:00","dateModified":"2015-10-31T11:20:00+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg"]}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.it\/blog\/#website","url":"https:\/\/ecobnb.it\/blog\/","name":"Ecobnb","description":"Trova il tuo Alloggio Ecosostenibile","publisher":{"@id":"https:\/\/ecobnb.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.it\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ecobnb.it\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/viaggiverdi"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg'><img width=\"536\" height=\"224\" src=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-536x224.jpg\" class=\"attachment-medium size-medium\" alt=\"Foliage in Italia\" srcset=\"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-536x224.jpg 536w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-344x144.jpg 344w, https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg 1170w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Foliage in Italia","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1170,"height":490,"file":"2015\/10\/Foliage-GIALLO1963-res.jpg","sizes":{"thumbnail":{"file":"Foliage-GIALLO1963-res-270x200.jpg","width":270,"height":200,"filesize":25927,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-270x200.jpg"},"medium":{"file":"Foliage-GIALLO1963-res-536x224.jpg","width":536,"height":224,"filesize":56745,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-536x224.jpg"},"large":{"file":"Foliage-GIALLO1963-res-870x490.jpg","width":870,"height":490,"filesize":225446,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-870x490.jpg"},"half":{"file":"Foliage-GIALLO1963-res-570x320.jpg","width":570,"height":320,"filesize":88176,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-570x320.jpg"},"portrait":{"file":"Foliage-GIALLO1963-res-344x144.jpg","width":344,"height":144,"filesize":22585,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res-344x144.jpg"},"full":{"file":"Foliage-GIALLO1963-res.jpg","width":1170,"height":490,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"Nikon F 3\nAis Micro Nikkor 200mm f:4\nVelvia","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"Nikon F 3\nAis Micro Nikkor 200mm f:4\nVelvia","orientation":1},"filesize":994245},"post":14078,"source_url":"https:\/\/ecobnb.it\/blog\/app\/uploads\/sites\/2\/2015\/10\/Foliage-GIALLO1963-res.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media\/14213"}],"collection":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.it\/blog\/wp-json\/wp\/v2\/users\/3"}]}}